{"id":5298,"date":"2024-07-28T12:00:40","date_gmt":"2024-07-28T12:00:40","guid":{"rendered":"https:\/\/ca2l.com\/portfolio-item\/riera-ordeix-shop\/"},"modified":"2024-07-28T12:02:41","modified_gmt":"2024-07-28T12:02:41","slug":"riera-ordeix-shop","status":"publish","type":"portfolio","link":"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/","title":{"rendered":"Riera Ordeix Shop"},"content":{"rendered":"<div  class='flex_column av-gv1913-952e62ca842f111554f60b4f7b02999a av_one_full  avia-builder-el-0  el_before_av_one_full  avia-builder-el-first  first flex_column_div av-hide-on-mobile  '     ><div  class='avia-slideshow av-lz5ibyak-1214fe0a396a1bb3f27c007c6402fdbb avia-slideshow-no scaling av_slideshow avia-slide-slider  avia-builder-el-1  avia-builder-el-no-sibling  av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 144.07027818448%;'><li  class='avia-slideshow-slide av-lz5ibyak-1214fe0a396a1bb3f27c007c6402fdbb__0  slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5273 avia-img-lazy-loading-not-5273\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/MGS48-RIERA-ORDEIX-SHOP-SANDRA-SOLER-STUDIO-PHOTO-MONTSE-CAPDEVILA-rieraordeix-02730.jpg\" width=\"683\" height=\"984\" title='MGS48 &amp; RIERA ORDEIX SHOP &amp; SANDRA SOLER STUDIO &amp; PHOTO MONTSE CAPDEVILA &amp; rieraordeix-02730' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/MGS48-RIERA-ORDEIX-SHOP-SANDRA-SOLER-STUDIO-PHOTO-MONTSE-CAPDEVILA-rieraordeix-02730.jpg 683w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/MGS48-RIERA-ORDEIX-SHOP-SANDRA-SOLER-STUDIO-PHOTO-MONTSE-CAPDEVILA-rieraordeix-02730-208x300.jpg 208w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/MGS48-RIERA-ORDEIX-SHOP-SANDRA-SOLER-STUDIO-PHOTO-MONTSE-CAPDEVILA-rieraordeix-02730-489x705.jpg 489w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/MGS48-RIERA-ORDEIX-SHOP-SANDRA-SOLER-STUDIO-PHOTO-MONTSE-CAPDEVILA-rieraordeix-02730-450x648.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/MGS48-RIERA-ORDEIX-SHOP-SANDRA-SOLER-STUDIO-PHOTO-MONTSE-CAPDEVILA-rieraordeix-02730-600x864.jpg 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-lz5ibyak-1214fe0a396a1bb3f27c007c6402fdbb__1  slide-2 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5276 avia-img-lazy-loading-not-5276\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02650.jpg\" width=\"656\" height=\"984\" title='rieraordeix-02650' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02650.jpg 656w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02650-200x300.jpg 200w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02650-470x705.jpg 470w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02650-450x675.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02650-600x900.jpg 600w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-lz5ibyak-1214fe0a396a1bb3f27c007c6402fdbb__2  slide-3 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5279 avia-img-lazy-loading-not-5279\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02656.jpg\" width=\"656\" height=\"984\" title='rieraordeix-02656' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02656.jpg 656w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02656-200x300.jpg 200w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02656-470x705.jpg 470w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02656-450x675.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02656-600x900.jpg 600w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-lz5ibyak-1214fe0a396a1bb3f27c007c6402fdbb__3  slide-4 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5282 avia-img-lazy-loading-not-5282\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02665.jpg\" width=\"1476\" height=\"984\" title='rieraordeix-02665' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02665.jpg 1476w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02665-300x200.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02665-1030x687.jpg 1030w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02665-768x512.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02665-705x470.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02665-450x300.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02665-600x400.jpg 600w\" sizes=\"(max-width: 1476px) 100vw, 1476px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-lz5ibyak-1214fe0a396a1bb3f27c007c6402fdbb__4  slide-5 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5285 avia-img-lazy-loading-not-5285\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02681.jpg\" width=\"1500\" height=\"984\" title='rieraordeix-02681' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02681.jpg 1500w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02681-300x197.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02681-1030x676.jpg 1030w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02681-768x504.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02681-705x462.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02681-450x295.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02681-600x394.jpg 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-lz5ibyak-1214fe0a396a1bb3f27c007c6402fdbb__5  slide-6 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5288 avia-img-lazy-loading-not-5288\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02696.jpg\" width=\"1476\" height=\"984\" title='rieraordeix-02696' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02696.jpg 1476w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02696-300x200.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02696-1030x687.jpg 1030w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02696-768x512.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02696-705x470.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02696-450x300.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02696-600x400.jpg 600w\" sizes=\"(max-width: 1476px) 100vw, 1476px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-lz5ibyak-1214fe0a396a1bb3f27c007c6402fdbb__6  slide-7 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5291 avia-img-lazy-loading-not-5291\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02716.jpg\" width=\"656\" height=\"984\" title='rieraordeix-02716' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02716.jpg 656w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02716-200x300.jpg 200w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02716-470x705.jpg 470w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02716-450x675.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02716-600x900.jpg 600w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-lz5ibyak-1214fe0a396a1bb3f27c007c6402fdbb__7  slide-8 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5294 avia-img-lazy-loading-not-5294\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02759.jpg\" width=\"1476\" height=\"984\" title='rieraordeix-02759' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02759.jpg 1476w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02759-300x200.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02759-1030x687.jpg 1030w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02759-768x512.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02759-705x470.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02759-450x300.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02759-600x400.jpg 600w\" sizes=\"(max-width: 1476px) 100vw, 1476px\" \/><\/div><\/li><\/ul><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='left-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Anterior\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-1'>Anterior<\/title>\n<desc id='av-svg-desc-1'>Anterior<\/desc>\n<path d=\"M14.464 27.84q0.832 0.832 0 1.536-0.832 0.832-1.536 0l-12.544-12.608q-0.768-0.768 0-1.6l12.544-12.608q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-11.456 11.904z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Anterior<\/span><\/a><a href='#next' class='next-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='right-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Seg\u00fcent\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-2' aria-describedby='av-svg-desc-2' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-2'>Seg\u00fcent<\/title>\n<desc id='av-svg-desc-2'>Seg\u00fcent<\/desc>\n<path d=\"M0.416 27.84l11.456-11.84-11.456-11.904q-0.832-0.832 0-1.536 0.832-0.832 1.536 0l12.544 12.608q0.768 0.832 0 1.6l-12.544 12.608q-0.704 0.832-1.536 0-0.832-0.704 0-1.536z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Seg\u00fcent<\/span><\/a><\/div><div class='avia-slideshow-dots avia-slideshow-controls'><a href='#1' class='goto-slide active' >1<\/a><a href='#2' class='goto-slide ' >2<\/a><a href='#3' class='goto-slide ' >3<\/a><a href='#4' class='goto-slide ' >4<\/a><a href='#5' class='goto-slide ' >5<\/a><a href='#6' class='goto-slide ' >6<\/a><a href='#7' class='goto-slide ' >7<\/a><a href='#8' class='goto-slide ' >8<\/a><\/div><\/div><\/div>\n<div  class='flex_column av-20wfdj-19c04d76ebbf14bae9dd1d39d5715233 av_one_full  avia-builder-el-2  el_after_av_one_full  avia-builder-el-last  first flex_column_div  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lz5ic6a1-68325194a6bacba82fa9e960c3096ab3\">\n#top .av-special-heading.av-lz5ic6a1-68325194a6bacba82fa9e960c3096ab3{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-lz5ic6a1-68325194a6bacba82fa9e960c3096ab3 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-lz5ic6a1-68325194a6bacba82fa9e960c3096ab3 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-lz5ic6a1-68325194a6bacba82fa9e960c3096ab3 av-special-heading-h1 blockquote modern-quote  avia-builder-el-3  el_before_av_textblock  avia-builder-el-first '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Riera Ordeix Shop<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-lz5id0ym-d13e1b2597a4b01c0601ba265e08dc8c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Arquitectura \/ Interiorisme<br \/>\n<strong>Sandra Soler<\/strong><\/p>\n<p>Ciutat<br \/>\n<strong>Vic<\/strong><\/p>\n<p>Fotografia<br \/>\n<strong>Montse Capdevila<\/strong><\/p>\n<\/div><\/section><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":5276,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[94],"class_list":["post-5298","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-retail-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riera Ordeix Shop - Lighting Projects - ca2l<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riera Ordeix Shop - Lighting Projects - ca2l\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/\" \/>\n<meta property=\"og:site_name\" content=\"Lighting Projects - ca2l\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ca2L.lighting\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-28T12:02:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02650.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"656\" \/>\n\t<meta property=\"og:image:height\" content=\"984\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/riera-ordeix-shop\\\/\",\"url\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/riera-ordeix-shop\\\/\",\"name\":\"Riera Ordeix Shop - Lighting Projects - ca2l\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/riera-ordeix-shop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/riera-ordeix-shop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/rieraordeix-02650.jpg\",\"datePublished\":\"2024-07-28T12:00:40+00:00\",\"dateModified\":\"2024-07-28T12:02:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/riera-ordeix-shop\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/riera-ordeix-shop\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/riera-ordeix-shop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/rieraordeix-02650.jpg\",\"contentUrl\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/rieraordeix-02650.jpg\",\"width\":656,\"height\":984},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/riera-ordeix-shop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riera Ordeix Shop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/\",\"name\":\"Lighting Projects - ca2l\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#organization\",\"name\":\"Lighting Projects - ca2l\",\"url\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ca2l-logohome4.png\",\"contentUrl\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ca2l-logohome4.png\",\"width\":340,\"height\":120,\"caption\":\"Lighting Projects - ca2l\"},\"image\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ca2L.lighting\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ca2l_lighting_projects\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/ca2l\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riera Ordeix Shop - Lighting Projects - ca2l","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/","og_locale":"ca_ES","og_type":"article","og_title":"Riera Ordeix Shop - Lighting Projects - ca2l","og_url":"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/","og_site_name":"Lighting Projects - ca2l","article_publisher":"https:\/\/www.facebook.com\/ca2L.lighting\/","article_modified_time":"2024-07-28T12:02:41+00:00","og_image":[{"width":656,"height":984,"url":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02650.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/","url":"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/","name":"Riera Ordeix Shop - Lighting Projects - ca2l","isPartOf":{"@id":"https:\/\/ca2l.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/#primaryimage"},"image":{"@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/#primaryimage"},"thumbnailUrl":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02650.jpg","datePublished":"2024-07-28T12:00:40+00:00","dateModified":"2024-07-28T12:02:41+00:00","breadcrumb":{"@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/#primaryimage","url":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02650.jpg","contentUrl":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/07\/rieraordeix-02650.jpg","width":656,"height":984},{"@type":"BreadcrumbList","@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/riera-ordeix-shop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ca2l.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Riera Ordeix Shop"}]},{"@type":"WebSite","@id":"https:\/\/ca2l.com\/ca\/#website","url":"https:\/\/ca2l.com\/ca\/","name":"Lighting Projects - ca2l","description":"","publisher":{"@id":"https:\/\/ca2l.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ca2l.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/ca2l.com\/ca\/#organization","name":"Lighting Projects - ca2l","url":"https:\/\/ca2l.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/ca2l.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/ca2l.com\/wp-content\/uploads\/2023\/10\/ca2l-logohome4.png","contentUrl":"https:\/\/ca2l.com\/wp-content\/uploads\/2023\/10\/ca2l-logohome4.png","width":340,"height":120,"caption":"Lighting Projects - ca2l"},"image":{"@id":"https:\/\/ca2l.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ca2L.lighting\/","https:\/\/www.instagram.com\/ca2l_lighting_projects\/","https:\/\/www.pinterest.com\/ca2l\/"]}]}},"_links":{"self":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio\/5298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/comments?post=5298"}],"version-history":[{"count":0,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio\/5298\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/media\/5276"}],"wp:attachment":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/media?parent=5298"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/tags?post=5298"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio_entries?post=5298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}