{"id":2323,"date":"2024-04-01T19:53:55","date_gmt":"2024-04-01T19:53:55","guid":{"rendered":"https:\/\/ca2l.com\/portfolio-item\/showroom-casa-delfin\/"},"modified":"2024-04-01T19:55:00","modified_gmt":"2024-04-01T19:55:00","slug":"showroom-casa-delfin","status":"publish","type":"portfolio","link":"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/","title":{"rendered":"Showroom Casa Delfin"},"content":{"rendered":"<div  class='flex_column av-lpxwtr-8f5ad8902ac920e63f8b906b51992660 av_one_full  avia-builder-el-0  el_before_av_one_full  avia-builder-el-first  first flex_column_div av-hide-on-mobile  '     ><div  class='avia-slideshow av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0 avia-slideshow-no scaling av_slideshow avia-slide-slider  avia-builder-el-1  avia-builder-el-no-sibling  av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 67.90450928382%;'><li  class='avia-slideshow-slide av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0__0  slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2289 avia-img-lazy-loading-not-2289\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/a2.jpg\" width=\"1131\" height=\"768\" title='a2' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/a2.jpg 1131w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/a2-300x204.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/a2-1030x699.jpg 1030w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/a2-768x522.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/a2-705x479.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/a2-450x306.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/a2-600x407.jpg 600w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0__1  slide-2 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2292 avia-img-lazy-loading-not-2292\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019238Anguita-Berengena-Casa-D.jpg\" width=\"1023\" height=\"768\" title='Anguita-Berengena Casa Delf\u00c3\u00adn-019238Anguita-Berengena Casa D' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019238Anguita-Berengena-Casa-D.jpg 1023w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019238Anguita-Berengena-Casa-D-300x225.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019238Anguita-Berengena-Casa-D-768x577.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019238Anguita-Berengena-Casa-D-705x529.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019238Anguita-Berengena-Casa-D-450x338.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019238Anguita-Berengena-Casa-D-600x450.jpg 600w\" sizes=\"(max-width: 1023px) 100vw, 1023px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0__2  slide-3 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2295 avia-img-lazy-loading-not-2295\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D.jpg\" width=\"1023\" height=\"768\" title='Anguita-Berengena Casa Delf\u00c3\u00adn-019302Anguita-Berengena Casa D' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D.jpg 1023w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D-300x225.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D-768x577.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D-705x529.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D-450x338.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D-600x450.jpg 600w\" sizes=\"(max-width: 1023px) 100vw, 1023px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0__3  slide-4 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2298 avia-img-lazy-loading-not-2298\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019305Anguita-Berengena-Casa-D.jpg\" width=\"1023\" height=\"768\" title='Anguita-Berengena Casa Delf\u00c3\u00adn-019305Anguita-Berengena Casa D' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019305Anguita-Berengena-Casa-D.jpg 1023w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019305Anguita-Berengena-Casa-D-300x225.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019305Anguita-Berengena-Casa-D-768x577.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019305Anguita-Berengena-Casa-D-705x529.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019305Anguita-Berengena-Casa-D-450x338.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019305Anguita-Berengena-Casa-D-600x450.jpg 600w\" sizes=\"(max-width: 1023px) 100vw, 1023px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0__4  slide-5 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2301 avia-img-lazy-loading-not-2301\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019314Anguita-Berengena-Casa-D.jpg\" width=\"1079\" height=\"768\" title='Anguita-Berengena Casa Delf\u00c3\u00adn-019314Anguita-Berengena Casa D' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019314Anguita-Berengena-Casa-D.jpg 1079w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019314Anguita-Berengena-Casa-D-300x214.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019314Anguita-Berengena-Casa-D-1030x733.jpg 1030w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019314Anguita-Berengena-Casa-D-768x547.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019314Anguita-Berengena-Casa-D-260x185.jpg 260w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019314Anguita-Berengena-Casa-D-705x502.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019314Anguita-Berengena-Casa-D-450x320.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019314Anguita-Berengena-Casa-D-600x427.jpg 600w\" sizes=\"(max-width: 1079px) 100vw, 1079px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0__5  slide-6 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2304 avia-img-lazy-loading-not-2304\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019337Anguita-Berengena-Casa-D.jpg\" width=\"1023\" height=\"768\" title='Anguita-Berengena Casa Delf\u00c3\u00adn-019337Anguita-Berengena Casa D' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019337Anguita-Berengena-Casa-D.jpg 1023w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019337Anguita-Berengena-Casa-D-300x225.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019337Anguita-Berengena-Casa-D-768x577.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019337Anguita-Berengena-Casa-D-705x529.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019337Anguita-Berengena-Casa-D-450x338.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019337Anguita-Berengena-Casa-D-600x450.jpg 600w\" sizes=\"(max-width: 1023px) 100vw, 1023px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0__6  slide-7 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2307 avia-img-lazy-loading-not-2307\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019344Anguita-Berengena-Casa-D.jpg\" width=\"1023\" height=\"768\" title='Anguita-Berengena Casa Delf\u00c3\u00adn-019344Anguita-Berengena Casa D' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019344Anguita-Berengena-Casa-D.jpg 1023w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019344Anguita-Berengena-Casa-D-300x225.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019344Anguita-Berengena-Casa-D-768x577.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019344Anguita-Berengena-Casa-D-705x529.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019344Anguita-Berengena-Casa-D-450x338.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019344Anguita-Berengena-Casa-D-600x450.jpg 600w\" sizes=\"(max-width: 1023px) 100vw, 1023px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0__7  slide-8 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2310 avia-img-lazy-loading-not-2310\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/f.jpg\" width=\"960\" height=\"631\" title='f' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/f.jpg 960w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/f-300x197.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/f-768x505.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/f-705x463.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/f-450x296.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/f-600x394.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0__8  slide-9 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2313 avia-img-lazy-loading-not-2313\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/h2.jpg\" width=\"928\" height=\"631\" title='h2' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/h2.jpg 928w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/h2-300x204.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/h2-768x522.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/h2-705x479.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/h2-450x306.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/h2-600x408.jpg 600w\" sizes=\"(max-width: 928px) 100vw, 928px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0__9  slide-10 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2316 avia-img-lazy-loading-not-2316\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/i.jpg\" width=\"924\" height=\"631\" title='i' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/i.jpg 924w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/i-300x205.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/i-768x524.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/i-705x481.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/i-450x307.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/i-600x410.jpg 600w\" sizes=\"(max-width: 924px) 100vw, 924px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-luhd9hio-ec3b5f6c9fd5b044ec863b02e6dfd2e0__10  slide-11 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2319 avia-img-lazy-loading-not-2319\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/j.jpg\" width=\"953\" height=\"631\" title='j' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/j.jpg 953w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/j-300x199.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/j-768x509.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/j-705x467.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/j-450x298.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/j-600x397.jpg 600w\" sizes=\"(max-width: 953px) 100vw, 953px\" \/><\/div><\/li><\/ul><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='left-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Anterior\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-1'>Anterior<\/title>\n<desc id='av-svg-desc-1'>Anterior<\/desc>\n<path d=\"M14.464 27.84q0.832 0.832 0 1.536-0.832 0.832-1.536 0l-12.544-12.608q-0.768-0.768 0-1.6l12.544-12.608q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-11.456 11.904z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Anterior<\/span><\/a><a href='#next' class='next-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='right-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Seg\u00fcent\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-2' aria-describedby='av-svg-desc-2' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-2'>Seg\u00fcent<\/title>\n<desc id='av-svg-desc-2'>Seg\u00fcent<\/desc>\n<path d=\"M0.416 27.84l11.456-11.84-11.456-11.904q-0.832-0.832 0-1.536 0.832-0.832 1.536 0l12.544 12.608q0.768 0.832 0 1.6l-12.544 12.608q-0.704 0.832-1.536 0-0.832-0.704 0-1.536z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Seg\u00fcent<\/span><\/a><\/div><div class='avia-slideshow-dots avia-slideshow-controls'><a href='#1' class='goto-slide active' >1<\/a><a href='#2' class='goto-slide ' >2<\/a><a href='#3' class='goto-slide ' >3<\/a><a href='#4' class='goto-slide ' >4<\/a><a href='#5' class='goto-slide ' >5<\/a><a href='#6' class='goto-slide ' >6<\/a><a href='#7' class='goto-slide ' >7<\/a><a href='#8' class='goto-slide ' >8<\/a><a href='#9' class='goto-slide ' >9<\/a><a href='#10' class='goto-slide ' >10<\/a><a href='#11' class='goto-slide ' >11<\/a><\/div><\/div><\/div>\n<div  class='flex_column av-2zvskv-7f3efc32753dfe24a822e7e876b3ce63 av_one_full  avia-builder-el-2  el_after_av_one_full  avia-builder-el-last  first flex_column_div  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-luhd9xxg-f1c314e7b81f362b89d696968f00bdfa\">\n#top .av-special-heading.av-luhd9xxg-f1c314e7b81f362b89d696968f00bdfa{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-luhd9xxg-f1c314e7b81f362b89d696968f00bdfa .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-luhd9xxg-f1c314e7b81f362b89d696968f00bdfa .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-luhd9xxg-f1c314e7b81f362b89d696968f00bdfa av-special-heading-h1 blockquote modern-quote  avia-builder-el-3  el_before_av_textblock  avia-builder-el-first '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Showroom Casa Delfin<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-luhdb0vf-b5da19153ca5a34a3815bca4a116f7e0 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Arquitectura \/ Interiorisme<br \/>\n<strong>Joan Anguita i Rafael Berengenar<\/strong><\/p>\n<p>Ciutat<br \/>\n<strong>Barcelona<\/strong><\/p>\n<p>Fotografia<br \/>\n<strong>Eugeni Pons<\/strong><\/p>\n<\/div><\/section><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":2295,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[94],"class_list":["post-2323","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-retail-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Showroom Casa Delfin - Lighting Projects - ca2l<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Showroom Casa Delfin - Lighting Projects - ca2l\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/\" \/>\n<meta property=\"og:site_name\" content=\"Lighting Projects - ca2l\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ca2L.lighting\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-01T19:55:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1023\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/showroom-casa-delfin\\\/\",\"url\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/showroom-casa-delfin\\\/\",\"name\":\"Showroom Casa Delfin - Lighting Projects - ca2l\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/showroom-casa-delfin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/showroom-casa-delfin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D.jpg\",\"datePublished\":\"2024-04-01T19:53:55+00:00\",\"dateModified\":\"2024-04-01T19:55:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/showroom-casa-delfin\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/showroom-casa-delfin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/showroom-casa-delfin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D.jpg\",\"contentUrl\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D.jpg\",\"width\":1023,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/showroom-casa-delfin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Showroom Casa Delfin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/\",\"name\":\"Lighting Projects - ca2l\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#organization\",\"name\":\"Lighting Projects - ca2l\",\"url\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ca2l-logohome4.png\",\"contentUrl\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ca2l-logohome4.png\",\"width\":340,\"height\":120,\"caption\":\"Lighting Projects - ca2l\"},\"image\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ca2L.lighting\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ca2l_lighting_projects\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/ca2l\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Showroom Casa Delfin - Lighting Projects - ca2l","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/","og_locale":"ca_ES","og_type":"article","og_title":"Showroom Casa Delfin - Lighting Projects - ca2l","og_url":"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/","og_site_name":"Lighting Projects - ca2l","article_publisher":"https:\/\/www.facebook.com\/ca2L.lighting\/","article_modified_time":"2024-04-01T19:55:00+00:00","og_image":[{"width":1023,"height":768,"url":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/","url":"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/","name":"Showroom Casa Delfin - Lighting Projects - ca2l","isPartOf":{"@id":"https:\/\/ca2l.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/#primaryimage"},"image":{"@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/#primaryimage"},"thumbnailUrl":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D.jpg","datePublished":"2024-04-01T19:53:55+00:00","dateModified":"2024-04-01T19:55:00+00:00","breadcrumb":{"@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/#primaryimage","url":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D.jpg","contentUrl":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/04\/Anguita-Berengena-Casa-DelfA\u00adn-019302Anguita-Berengena-Casa-D.jpg","width":1023,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/showroom-casa-delfin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ca2l.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Showroom Casa Delfin"}]},{"@type":"WebSite","@id":"https:\/\/ca2l.com\/ca\/#website","url":"https:\/\/ca2l.com\/ca\/","name":"Lighting Projects - ca2l","description":"","publisher":{"@id":"https:\/\/ca2l.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ca2l.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/ca2l.com\/ca\/#organization","name":"Lighting Projects - ca2l","url":"https:\/\/ca2l.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/ca2l.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/ca2l.com\/wp-content\/uploads\/2023\/10\/ca2l-logohome4.png","contentUrl":"https:\/\/ca2l.com\/wp-content\/uploads\/2023\/10\/ca2l-logohome4.png","width":340,"height":120,"caption":"Lighting Projects - ca2l"},"image":{"@id":"https:\/\/ca2l.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ca2L.lighting\/","https:\/\/www.instagram.com\/ca2l_lighting_projects\/","https:\/\/www.pinterest.com\/ca2l\/"]}]}},"_links":{"self":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio\/2323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/comments?post=2323"}],"version-history":[{"count":0,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio\/2323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/media\/2295"}],"wp:attachment":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/media?parent=2323"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/tags?post=2323"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio_entries?post=2323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}