{"id":1566,"date":"2024-03-17T16:11:04","date_gmt":"2024-03-17T16:11:04","guid":{"rendered":"https:\/\/ca2l.com\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/"},"modified":"2024-03-17T16:12:20","modified_gmt":"2024-03-17T16:12:20","slug":"palacio-de-ferias-y-congresos-de-malaga","status":"publish","type":"portfolio","link":"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/","title":{"rendered":"Palacio de Ferias y Congresos de M\u00e1laga"},"content":{"rendered":"<div  class='flex_column av-13rsen-0da4de6a02465dc463d438d50eb24056 av_one_full  avia-builder-el-0  el_before_av_one_full  avia-builder-el-first  first flex_column_div av-hide-on-mobile  '     ><div  class='avia-slideshow av-ltvpnyqt-62f474127ed28ebcfd5eb70b3bf109d9 avia-slideshow-no scaling av_slideshow avia-slide-slider  avia-builder-el-1  avia-builder-el-no-sibling  av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 41.125%;'><li  class='avia-slideshow-slide av-ltvpnyqt-62f474127ed28ebcfd5eb70b3bf109d9__0  slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1553 avia-img-lazy-loading-not-1553\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/fotos-nocturnas-001-800x600-1.jpg\" width=\"800\" height=\"329\" title='fotos nocturnas 001 [800x600]' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/fotos-nocturnas-001-800x600-1.jpg 800w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/fotos-nocturnas-001-800x600-1-300x123.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/fotos-nocturnas-001-800x600-1-768x316.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/fotos-nocturnas-001-800x600-1-705x290.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/fotos-nocturnas-001-800x600-1-450x185.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/fotos-nocturnas-001-800x600-1-600x247.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-ltvpnyqt-62f474127ed28ebcfd5eb70b3bf109d9__1  slide-2 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1559 avia-img-lazy-loading-not-1559\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1.jpg\" width=\"800\" height=\"554\" title='palacio13-DSCF0255 [800x600]' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1.jpg 800w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1-300x208.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1-768x532.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1-705x488.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1-450x312.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1-600x416.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-ltvpnyqt-62f474127ed28ebcfd5eb70b3bf109d9__2  slide-3 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1556 avia-img-lazy-loading-not-1556\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio03-DSCF0279-800x600-1.jpg\" width=\"800\" height=\"533\" title='palacio03-DSCF0279 [800x600]' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio03-DSCF0279-800x600-1.jpg 800w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio03-DSCF0279-800x600-1-300x200.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio03-DSCF0279-800x600-1-768x512.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio03-DSCF0279-800x600-1-705x470.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio03-DSCF0279-800x600-1-450x300.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio03-DSCF0279-800x600-1-600x400.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-ltvpnyqt-62f474127ed28ebcfd5eb70b3bf109d9__3  slide-4 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1562 avia-img-lazy-loading-not-1562\"  src=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio20-DSCF0282-800x600-1.jpg\" width=\"800\" height=\"533\" title='palacio20-DSCF0282 [800x600]' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio20-DSCF0282-800x600-1.jpg 800w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio20-DSCF0282-800x600-1-300x200.jpg 300w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio20-DSCF0282-800x600-1-768x512.jpg 768w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio20-DSCF0282-800x600-1-705x470.jpg 705w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio20-DSCF0282-800x600-1-450x300.jpg 450w, https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio20-DSCF0282-800x600-1-600x400.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/li><\/ul><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='left-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Anterior\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-1'>Anterior<\/title>\n<desc id='av-svg-desc-1'>Anterior<\/desc>\n<path d=\"M14.464 27.84q0.832 0.832 0 1.536-0.832 0.832-1.536 0l-12.544-12.608q-0.768-0.768 0-1.6l12.544-12.608q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-11.456 11.904z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Anterior<\/span><\/a><a href='#next' class='next-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='right-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Seg\u00fcent\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-2' aria-describedby='av-svg-desc-2' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-2'>Seg\u00fcent<\/title>\n<desc id='av-svg-desc-2'>Seg\u00fcent<\/desc>\n<path d=\"M0.416 27.84l11.456-11.84-11.456-11.904q-0.832-0.832 0-1.536 0.832-0.832 1.536 0l12.544 12.608q0.768 0.832 0 1.6l-12.544 12.608q-0.704 0.832-1.536 0-0.832-0.704 0-1.536z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Seg\u00fcent<\/span><\/a><\/div><div class='avia-slideshow-dots avia-slideshow-controls'><a href='#1' class='goto-slide active' >1<\/a><a href='#2' class='goto-slide ' >2<\/a><a href='#3' class='goto-slide ' >3<\/a><a href='#4' class='goto-slide ' >4<\/a><\/div><\/div><\/div>\n<div  class='flex_column av-29h7bz-9109be89c801f6cd592aa46f665b6a86 av_one_full  avia-builder-el-2  el_after_av_one_full  avia-builder-el-last  first flex_column_div  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ltvpo5p4-4d72f30f710a5ec782e812b60f2f1619\">\n#top .av-special-heading.av-ltvpo5p4-4d72f30f710a5ec782e812b60f2f1619{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-ltvpo5p4-4d72f30f710a5ec782e812b60f2f1619 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-ltvpo5p4-4d72f30f710a5ec782e812b60f2f1619 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-ltvpo5p4-4d72f30f710a5ec782e812b60f2f1619 av-special-heading-h1 blockquote modern-quote  avia-builder-el-3  el_before_av_textblock  avia-builder-el-first '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Palacio de Ferias y Congresos de M\u00e1laga<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-ltvppwn8-64a6f77fbfc85e3a12bc3d2ebe82c755 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Arquitectura \/ Interiorisme<br \/>\n<strong>Palacio Ferias y Congresos<\/strong><\/p>\n<p>Ciutat<br \/>\n<strong>M\u00e1laga<\/strong><\/p>\n<p>Fotografia<br \/>\n<strong>Ca2L<\/strong><\/p>\n<\/div><\/section><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":1559,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[75],"class_list":["post-1566","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-espacis-exteriors-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palacio de Ferias y Congresos de M\u00e1laga - Lighting Projects - ca2l<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palacio de Ferias y Congresos de M\u00e1laga - Lighting Projects - ca2l\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/\" \/>\n<meta property=\"og:site_name\" content=\"Lighting Projects - ca2l\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ca2L.lighting\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-17T16:12:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/palacio-de-ferias-y-congresos-de-malaga\\\/\",\"url\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/palacio-de-ferias-y-congresos-de-malaga\\\/\",\"name\":\"Palacio de Ferias y Congresos de M\u00e1laga - Lighting Projects - ca2l\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/palacio-de-ferias-y-congresos-de-malaga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/palacio-de-ferias-y-congresos-de-malaga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/palacio13-DSCF0255-800x600-1.jpg\",\"datePublished\":\"2024-03-17T16:11:04+00:00\",\"dateModified\":\"2024-03-17T16:12:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/palacio-de-ferias-y-congresos-de-malaga\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/palacio-de-ferias-y-congresos-de-malaga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/palacio-de-ferias-y-congresos-de-malaga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/palacio13-DSCF0255-800x600-1.jpg\",\"contentUrl\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/palacio13-DSCF0255-800x600-1.jpg\",\"width\":800,\"height\":554},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/portfolio-item\\\/palacio-de-ferias-y-congresos-de-malaga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palacio de Ferias y Congresos de M\u00e1laga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/\",\"name\":\"Lighting Projects - ca2l\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#organization\",\"name\":\"Lighting Projects - ca2l\",\"url\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ca2l-logohome4.png\",\"contentUrl\":\"https:\\\/\\\/ca2l.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ca2l-logohome4.png\",\"width\":340,\"height\":120,\"caption\":\"Lighting Projects - ca2l\"},\"image\":{\"@id\":\"https:\\\/\\\/ca2l.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ca2L.lighting\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ca2l_lighting_projects\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/ca2l\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palacio de Ferias y Congresos de M\u00e1laga - Lighting Projects - ca2l","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/","og_locale":"ca_ES","og_type":"article","og_title":"Palacio de Ferias y Congresos de M\u00e1laga - Lighting Projects - ca2l","og_url":"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/","og_site_name":"Lighting Projects - ca2l","article_publisher":"https:\/\/www.facebook.com\/ca2L.lighting\/","article_modified_time":"2024-03-17T16:12:20+00:00","og_image":[{"width":800,"height":554,"url":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/","url":"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/","name":"Palacio de Ferias y Congresos de M\u00e1laga - Lighting Projects - ca2l","isPartOf":{"@id":"https:\/\/ca2l.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/#primaryimage"},"image":{"@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/#primaryimage"},"thumbnailUrl":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1.jpg","datePublished":"2024-03-17T16:11:04+00:00","dateModified":"2024-03-17T16:12:20+00:00","breadcrumb":{"@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/#primaryimage","url":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1.jpg","contentUrl":"https:\/\/ca2l.com\/wp-content\/uploads\/2024\/03\/palacio13-DSCF0255-800x600-1.jpg","width":800,"height":554},{"@type":"BreadcrumbList","@id":"https:\/\/ca2l.com\/ca\/portfolio-item\/palacio-de-ferias-y-congresos-de-malaga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ca2l.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Palacio de Ferias y Congresos de M\u00e1laga"}]},{"@type":"WebSite","@id":"https:\/\/ca2l.com\/ca\/#website","url":"https:\/\/ca2l.com\/ca\/","name":"Lighting Projects - ca2l","description":"","publisher":{"@id":"https:\/\/ca2l.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ca2l.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/ca2l.com\/ca\/#organization","name":"Lighting Projects - ca2l","url":"https:\/\/ca2l.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/ca2l.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/ca2l.com\/wp-content\/uploads\/2023\/10\/ca2l-logohome4.png","contentUrl":"https:\/\/ca2l.com\/wp-content\/uploads\/2023\/10\/ca2l-logohome4.png","width":340,"height":120,"caption":"Lighting Projects - ca2l"},"image":{"@id":"https:\/\/ca2l.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ca2L.lighting\/","https:\/\/www.instagram.com\/ca2l_lighting_projects\/","https:\/\/www.pinterest.com\/ca2l\/"]}]}},"_links":{"self":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio\/1566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/comments?post=1566"}],"version-history":[{"count":0,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio\/1566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/media\/1559"}],"wp:attachment":[{"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/media?parent=1566"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/tags?post=1566"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/ca2l.com\/ca\/wp-json\/wp\/v2\/portfolio_entries?post=1566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}